{"id":185,"date":"2024-06-19T17:48:30","date_gmt":"2024-06-19T17:48:30","guid":{"rendered":"https:\/\/exa.unne.edu.ar\/poee-web\/?page_id=185"},"modified":"2024-08-09T15:09:25","modified_gmt":"2024-08-09T15:09:25","slug":"diplomatura-robotica","status":"publish","type":"page","link":"https:\/\/exa.unne.edu.ar\/poee-web\/index.php\/diplomatura-robotica\/","title":{"rendered":""},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"185\" class=\"elementor elementor-185\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-92271d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92271d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d7b817\" data-id=\"5d7b817\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4918f15 elementor-widget elementor-widget-image\" data-id=\"4918f15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"284\" src=\"https:\/\/exa.unne.edu.ar\/poee-web\/wp-content\/uploads\/2024\/07\/Licenciatura-en-Didactica-de-la-Matematica-8-1024x284.png\" class=\"attachment-large size-large wp-image-287\" alt=\"Diplomatura en programaci\u00f3n y robotica educativa\" srcset=\"https:\/\/exa.unne.edu.ar\/poee-web\/wp-content\/uploads\/2024\/07\/Licenciatura-en-Didactica-de-la-Matematica-8-1024x284.png 1024w, https:\/\/exa.unne.edu.ar\/poee-web\/wp-content\/uploads\/2024\/07\/Licenciatura-en-Didactica-de-la-Matematica-8-300x83.png 300w, https:\/\/exa.unne.edu.ar\/poee-web\/wp-content\/uploads\/2024\/07\/Licenciatura-en-Didactica-de-la-Matematica-8-768x213.png 768w, https:\/\/exa.unne.edu.ar\/poee-web\/wp-content\/uploads\/2024\/07\/Licenciatura-en-Didactica-de-la-Matematica-8-1536x427.png 1536w, https:\/\/exa.unne.edu.ar\/poee-web\/wp-content\/uploads\/2024\/07\/Licenciatura-en-Didactica-de-la-Matematica-8-216x60.png 216w, https:\/\/exa.unne.edu.ar\/poee-web\/wp-content\/uploads\/2024\/07\/Licenciatura-en-Didactica-de-la-Matematica-8.png 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec5f19b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec5f19b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9429d4c\" data-id=\"9429d4c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7aabb98 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"7aabb98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1281\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1281\" aria-expanded=\"false\">Sobre la propuesta<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1282\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1282\" aria-expanded=\"false\">Plan de Estudios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1283\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1283\" aria-expanded=\"false\">Cuerpo acad\u00e9mico y de gesti\u00f3n<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1284\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1284\" aria-expanded=\"false\">Destinatarios<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1285\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1285\" aria-expanded=\"false\">Inscripci\u00f3n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1281\" aria-expanded=\"false\">Sobre la propuesta<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1281\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1281\" tabindex=\"0\" hidden=\"false\"><p><b>Denominaci\u00f3n:\u00a0<\/b>Diplomatura de Programaci\u00f3n y Rob\u00f3tica Educativa<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p><b>Plan de Estudios:<\/b><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">RES &#8211; 2024 &#8211; 4 &#8211; CD-EXA # UNNE<\/span><\/p><p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><p><b>Informaci\u00f3n de contacto<\/b><b>:<\/b><span style=\"font-weight: 400;\">\u00a0raquel.petris@comunidad.unne.edu.ar\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><p><b>Objetivos institucionales<\/b><\/p><p><span style=\"font-weight: 400;\">Acompa\u00f1ar las pol\u00edticas p\u00fablicas orientadas a incorporar en la educaci\u00f3n b\u00e1sica conceptos y herramientas para lograr ciudadanos activos y cr\u00edticos de este mundo tecnol\u00f3gicamente intensivo, mediante la formaci\u00f3n de los docentes del nivel primario, secundario y terciario en el manejo de tecnolog\u00edas de programaci\u00f3n y rob\u00f3tica, adecuadas a los niveles preuniversitarios.<\/span><\/p><p>\u00a0<\/p><p><b>Formaci\u00f3n<\/b><\/p><p><span style=\"font-weight: 400;\">Como resultado de esta propuesta formativa se espera que los participantes (en este caso, el docente de las escuelas), adquiera las siguientes capacidades y competencias:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Comprender la importancia de la incorporaci\u00f3n en las escuelas de los temas propios de las Ciencias de la Computaci\u00f3n como forma de contribuir con la formaci\u00f3n de ciudadanos que entiendan mejor el mundo tecnol\u00f3gico que nos rodea.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Entender y aplicar las t\u00e9cnicas b\u00e1sicas de programaci\u00f3n y de rob\u00f3tica para desenvolverse adecuadamente en los nuevos contextos educativos.\u00a0<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Conocer y aplicar un m\u00e9todo de resoluci\u00f3n de problemas que facilitar\u00e1 la ense\u00f1anza de la programaci\u00f3n, y que puede ser extendido a otros \u00e1mbitos.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Aplicar e integrar nuevos enfoques did\u00e1cticos que promueven el aprendizaje activo y colaborativo.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Dise\u00f1ar actividades de ense\u00f1anza utilizando dispositivos innovadores que ofrecen retos y desaf\u00edos motivadores para los estudiantes.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Estimular en sus estudiantes la exploraci\u00f3n temprana de conocimientos cient\u00edficos y tecnol\u00f3gicos, integrando conceptos de matem\u00e1tica, mec\u00e1nica, ingenier\u00eda y electr\u00f3nica.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Fortalecer en sus estudiantes la capacidad de abstracci\u00f3n, m\u00e1s all\u00e1 de herramientas puntuales, brindando la posibilidad de aplicar los conocimientos en diferentes dispositivos y sistemas.<\/span><\/li><\/ul><p><b>Carga horaria total:\u00a0<\/b><span style=\"font-weight: 400;\">250 h. reloj.<\/span><\/p><p>\u00a0<\/p><p><b>Duraci\u00f3n del programa en meses:\u00a0<\/b><span style=\"font-weight: 400;\">8 (ocho)<\/span><span style=\"font-weight: 400;\"> meses.<\/span><b>\u00a0<\/b><\/p><p><b>Inicio: <\/b><span style=\"font-weight: 400;\">\u00a0\u00a0<\/span><span style=\"font-weight: 400;\">agosto 2024\u00a0<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1282\" aria-expanded=\"false\">Plan de Estudios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1282\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1282\" tabindex=\"0\" hidden=\"hidden\"><p><b>M\u00f3dulo 1:<\/b> <b>Programaci\u00f3n visual basada en bloques<\/b><\/p><p><b>Carga horaria: <\/b><span style=\"font-weight: 400;\">50 hs.<\/span><\/p><p><b>Objetivos:\u00a0<\/b><\/p><p><span style=\"font-weight: 400;\">Que los docentes<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Conozcan los conceptos b\u00e1sicos de programaci\u00f3n.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Conozcan herramientas de programaci\u00f3n visual basada en bloques.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Desarrollen actividades que permitan a los participantes crear programas sencillos y resolver problemas utilizando un enfoque de resoluci\u00f3n de problemas<\/span><\/li><\/ul><p><b>Contenidos m\u00ednimos:\u00a0<\/b><\/p><ul><li style=\"list-style-type: none;\"><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Introducci\u00f3n a la programaci\u00f3n. Prop\u00f3sitos generales. Contenidos Estrategias did\u00e1cticas. Estrategias de evaluaci\u00f3n. Herramientas. M\u00e9todo de resoluci\u00f3n de problema. Definir una estrategia general. Descomponer el problema en partes y nombrar adecuadamente las partes. Legibilidad.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Presentaci\u00f3n de Pilas Bloques. Aut\u00f3matas, comandos y procedimientos. Repetici\u00f3n simple. Alternativas condicionales. Repetici\u00f3n condicional. Actividades desenchufadas. Programar actividades con PilasBloques.<\/span><\/li><\/ul><\/li><\/ul><ul><li aria-level=\"1\"><span style=\"font-weight: 400;\">Programaci\u00f3n con Scratch: Introducci\u00f3n. Elementos del entorno. Descripci\u00f3n de la Interfaz: Escenarios. Pesta\u00f1as. Programas (scripts), disfraces y sonidos. Seleccionar objetos. Arrastrar, soltar. Variables. Estructuras de control. Proyectos con Scratch.<\/span><\/li><\/ul><p><b>M\u00f3dulo 2:<\/b> <b>Programaci\u00f3n de placas Arduino<\/b><\/p><p><b>Carga horaria: <\/b><span style=\"font-weight: 400;\">50 hs.<\/span><\/p><p><b>Objetivos:<\/b><\/p><p><span style=\"font-weight: 400;\">Que los docentes<\/span><b>:\u00a0<\/b><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Conozcan plataformas de hardware y software abierto que se pueden utilizar para generar proyectos de rob\u00f3tica.\u00a0<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Realicen pr\u00e1cticas dise\u00f1ando circuitos y su codificaci\u00f3n para la resoluci\u00f3n de ejercicios simples, que puedan trasladarse al aula sin dificultad.\u00a0<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Profundicen el desarrollo de competencias, tales como el trabajo en grupo, la creatividad, la responsabilidad, entre otras, necesarias para el desarrollo profesional y para los nuevos desaf\u00edos que plantea la escuela del futuro.<\/span><\/li><\/ul><p><b>Contenidos m\u00ednimos:\u00a0<\/b><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Introducci\u00f3n a las plataformas de hardware abierto y su relaci\u00f3n con la educaci\u00f3n. Conceptos de computaci\u00f3n f\u00edsica.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Arduino. Caracter\u00edsticas y partes de las placas Arduino. La placa Arduino UNO. Componentes. Conociendo el circuito. Entender la electricidad: corriente, voltaje, resistencias. Sensores. Definici\u00f3n. \u00bfQu\u00e9 miden los sensores? Tipos. Aspectos a tener en cuenta. Actuadores. Definici\u00f3n. Ejemplos. Aspectos a tener en cuenta.\u00a0<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Programaci\u00f3n en Arduino. Arduino: Circuito y C\u00f3digo. El IDE de Arduino. Caracter\u00edsticas. Estructura de un programa: setup() y loop(). Nuevos comandos. Documentaci\u00f3n.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Rob\u00f3tica. Aplicaci\u00f3n de circuitos y programaci\u00f3n Arduino. Circuitos: sensores-placa, controladores y otros componentes electr\u00f3nicos. Dise\u00f1o de actividades educativas aplicando las tecnolog\u00edas dadas.\u00a0<\/span><\/li><\/ul><p><b>M\u00f3dulo 3:<\/b> <b>Programaci\u00f3n con Python<\/b><\/p><p><b>Carga horaria: 5<\/b><span style=\"font-weight: 400;\">0 hs.<\/span><\/p><p><b>Objetivos:<\/b><\/p><p><span style=\"font-weight: 400;\">Que los docentes<\/span><b>:\u00a0<\/b><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Adquieran las habilidades necesarias para resolver problemas e implementar su soluci\u00f3n a trav\u00e9s de la programaci\u00f3n en Python orientado a la rob\u00f3tica<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Se introduzcan en la programaci\u00f3n y la automatizaci\u00f3n de tareas del mundo real.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Se familiarice con entornos de programaci\u00f3n m\u00e1s profesionales y aprecie el potencial que ofrecen.<\/span><\/li><\/ul><p><b>Contenidos m\u00ednimos:\u00a0<\/b><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Introducci\u00f3n a Python: Introducir Python como un lenguaje de programaci\u00f3n vers\u00e1til. Instalaci\u00f3n y configuraci\u00f3n del entorno de desarrollo Python.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Sintaxis b\u00e1sica de Python. Variables, tipos de datos y operadores. Estructuras de control (if, for, while). Funciones y modularidad.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Conceptos de programaci\u00f3n orientada a objetos: Introducci\u00f3n a la programaci\u00f3n orientada a objetos (POO). Clases, objetos y m\u00e9todos en Python.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Simulaci\u00f3n de robots: Introducir simuladores de robots como \u00a0EV3basis. Control de robots simulados mediante Python.<\/span><\/li><\/ul><p>\u00a0<\/p><p><b>M\u00f3dulo 4:<\/b> <b>Programaci\u00f3n de microcontroladores<\/b><\/p><p><b>Carga horaria: <\/b>5<span style=\"font-weight: 400;\">0 hs.<\/span><\/p><p><b>Objetivos:<\/b><\/p><p><span style=\"font-weight: 400;\">Que los docentes<\/span><b>:\u00a0<\/b><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Adquieran conocimientos de programaci\u00f3n y rob\u00f3tica necesarios para comprender y transformar el entorno, y para situarse como participantes activos en un mundo en permanente cambio.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Comprendan las principales caracter\u00edsticas de los recursos: programas, placas de control, protocolos y plataformas apelando a la creatividad y a la experimentaci\u00f3n directa.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Construyan una base de conocimientos b\u00e1sicos de electr\u00f3nica y rob\u00f3tica.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Adquieran habilidades anal\u00edticas, de resoluci\u00f3n de problemas, de dise\u00f1o y de pensamiento computacional mediante el desarrollo de proyectos de rob\u00f3tica y de programaci\u00f3n f\u00edsica.<\/span><\/li><\/ul><p><b>Contenidos m\u00ednimos:\u00a0<\/b><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Contexto de la Rob\u00f3tica Educativa. Elementos de un sistema rob\u00f3tico. Procesos.\u00a0<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Entradas y salidas digitales. Entradas y salidas anal\u00f3gicas. Sensores y actuadores.\u00a0<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Comunicaci\u00f3n serie -Protocolos. Simuladores: Disponibilidad y selecci\u00f3n.\u00a0<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Aplicaciones usando simuladores. Aplicaciones en Automatizaci\u00f3n Industrial. Aplicaciones en Dom\u00f3tica. Aplicaciones en Medicina. Aplicaciones en Agroindustria.\u00a0<\/span><\/li><\/ul><p>\u00a0<\/p><p><b>M\u00f3dulo 5:<\/b> <b>Enfoques did\u00e1cticos para la programaci\u00f3n<\/b><\/p><p><b>Carga horaria: <\/b><span style=\"font-weight: 400;\">50 hs.<\/span><\/p><p><b>Objetivos a lograr:<\/b><\/p><p><span style=\"font-weight: 400;\">Que los docentes<\/span><b>:\u00a0<\/b><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Comprendan la necesidad de incorporar las ciencias de la computaci\u00f3n en las escuelas y entender las pol\u00edticas educativas orientadas en este sentido.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Conozcan las competencias y capacidades que se buscan en el proceso de alfabetizaci\u00f3n actual.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Dise\u00f1ar y evaluar actividades de aprendizaje sobre temas de Ciencias de la Computaci\u00f3n.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Conozcan y apliquen las metodolog\u00edas educativas orientadas a la ense\u00f1anza activa y significativa.\u00a0<\/span><\/li><\/ul><p><b>Contenidos m\u00ednimos:\u00a0<\/b><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">La relevancia de las ciencias de la computaci\u00f3n en las escuelas: Introducci\u00f3n. Argumentos: Necesidad de formar ciudadanos cr\u00edticos. Pol\u00edticas p\u00fablicas sobre Educaci\u00f3n. Programaci\u00f3n y rob\u00f3tica como campos emergentes del saber. El enfoque STEM, aprendizaje basado en proyectos, el foco en la creatividad. N\u00facleos de Aprendizajes Prioritarios para educaci\u00f3n digital, programaci\u00f3n y rob\u00f3tica (NAP EDPR).\u00a0<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Capacidades y competencias de educaci\u00f3n digital dimensiones y ejes destacados: Creatividad e innovaci\u00f3n. Comunicaci\u00f3n y colaboraci\u00f3n. Informaci\u00f3n y representaci\u00f3n. Participaci\u00f3n responsable y solidaria. Pensamiento cr\u00edtico. Uso aut\u00f3nomo de las TIC.\u00a0<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Estrategias did\u00e1cticas para la ense\u00f1anza de la programaci\u00f3n y la rob\u00f3tica: Aprendizajes basados en la indagaci\u00f3n y en proyectos. Elementos para elaborar una programaci\u00f3n did\u00e1ctica: Componentes y realizaci\u00f3n. Metodolog\u00edas de trabajo: trabajo en equipo, roles.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Implementaci\u00f3n y Evaluaci\u00f3n. Integraci\u00f3n de la programaci\u00f3n y la rob\u00f3tica en la escuela: desarrollo de secuencias did\u00e1cticas. Din\u00e1micas de Trabajo. Ficha t\u00e9cnica. R\u00fabricas para la evaluaci\u00f3n de competencias.<\/span><\/li><\/ul><p>\u00a0<\/p><p><b><i>Modalidad:\u00a0<\/i><\/b><\/p><p><span style=\"font-weight: 400;\">La Diplomatura se implementa bajo la opci\u00f3n a distancia.<\/span><\/p><p><span style=\"font-weight: 400;\">Se llevar\u00e1 a cabo mediante una combinaci\u00f3n de clases magistrales, sesiones pr\u00e1cticas en vivo, tutoriales grabados, y trabajo aut\u00f3nomo guiado. Se realizan sesiones presenciales para la interacci\u00f3n con los componentes f\u00edsicos que se requieren en rob\u00f3tica. Se utilizar\u00e1n plataformas de aprendizaje en l\u00ednea y herramientas de colaboraci\u00f3n para facilitar la interacci\u00f3n entre los estudiantes y el equipo docente.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1283\" aria-expanded=\"false\">Cuerpo acad\u00e9mico y de gesti\u00f3n<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1283\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1283\" tabindex=\"0\" hidden=\"hidden\"><p><b><i>Coordinaci\u00f3n<\/i><\/b><\/p><ul><li><span style=\"font-weight: 400;\">Mgter. Gladys Dapozo (Coordinaci\u00f3n Acad\u00e9mica)<\/span><\/li><li><span style=\"font-weight: 400;\">Mgter Raquel Petris (Coordinaci\u00f3n Ejecutiva)<\/span><\/li><\/ul><p><b><i>Comit\u00e9 Asesor:\u00a0<\/i><\/b><\/p><ul><li><span style=\"font-weight: 400;\">Dr. Ing. Emanuel Irraz\u00e1bal<\/span><\/li><li><span style=\"font-weight: 400;\">Ing. Jerem\u00edas Garc\u00eda Cabrera\u00a0<\/span><\/li><li><span style=\"font-weight: 400;\">Mgter. Cristina Greiner<\/span><\/li><li><span style=\"font-weight: 400;\">Lic. Yanina Medina<\/span><\/li><\/ul><p><b><i>Equipo Docente<\/i><\/b><\/p><ul><li><span style=\"font-weight: 400;\">Lic. Alonso, Juan Manuel<\/span><\/li><li><span style=\"font-weight: 400;\">Lic. Armana, Silvana<\/span><\/li><li><span style=\"font-weight: 400;\">Lic. Badaracco, Numa Hern\u00e1n<\/span><\/li><li><span style=\"font-weight: 400;\">Lic. B\u00e1ez, Edgar Dar\u00edo<\/span><\/li><li><span style=\"font-weight: 400;\">Lic. Carruthers, Juan Andr\u00e9s<\/span><\/li><li><span style=\"font-weight: 400;\">Lic. Company, Ana Mar\u00eda<\/span><\/li><li><span style=\"font-weight: 400;\">Lic. Esp\u00edndola, Mar\u00eda Cecilia<\/span><\/li><li><span style=\"font-weight: 400;\">Ing. Depiaggio, Alejandro Alberto<\/span><\/li><li><span style=\"font-weight: 400;\">Lic. Lezcano, Andrea<\/span><\/li><li><span style=\"font-weight: 400;\">Lic. Petris, Raquel Herminia<\/span><\/li><li><span style=\"font-weight: 400;\">Lic. Princich, Fernando Luis<\/span><\/li><li><span style=\"font-weight: 400;\">Lic. Sambrana, Iv\u00e1n<\/span><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1284\" aria-expanded=\"false\">Destinatarios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1284\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1284\" tabindex=\"0\" hidden=\"hidden\"><p><span style=\"font-weight: 400;\">Docentes de las escuelas de los niveles primario, secundario y terciario de la regi\u00f3n de influencia de la universidad, con conocimientos de inform\u00e1tica b\u00e1sica y disponibilidad de computadora con conexi\u00f3n a Internet.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1285\" aria-expanded=\"false\">Inscripci\u00f3n<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1285\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1285\" tabindex=\"0\" hidden=\"hidden\"><p><b>PREINSCRIPCI\u00d3N<\/b><\/p><p><span style=\"font-weight: 400;\">La Diplomatura tendr\u00e1 una instancia de pre-inscripci\u00f3n habilitada hasta el 5 de septiembre de 2024:\u00a0 <\/span><\/p><p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSejvrBlzpznzIneh3EfPrMzjnN1cNJFW6A7zv9QJQEeXHMefg\/viewform?pli=1\"><span style=\"font-weight: 400; color: #000080; text-decoration: underline;\">Pre-inscribite haciendo click aqu\u00ed<\/span><\/a><\/span><\/p><p>La Coordinaci\u00f3n enviar\u00e1 un correo electr\u00f3nico a la persona pre inscripta asignando la vacante en la Diplomatura e indicando los medios de pago (transferencia o tarjeta de cr\u00e9dito en un pago).<\/p><p><strong>Inscripci\u00f3n:<\/strong><\/p><p>Para confirmar la vacante deber\u00e1 enviar la documentaci\u00f3n solicitada y el comprobante de pago del arancel correspondiente antes del 5 de agosto de 2024.<\/p><p>Pre-inscripci\u00f3n: 28 de junio al 22 de julio 2024<\/p><p>Inscripci\u00f3n definitiva: hasta el 5 de agosto 2024 o hasta completar las vacantes.<\/p><p><strong>Requisitos de admisi\u00f3n: <\/strong><\/p><p>&#8211; Certificado que acredite el ejercicio de la docencia en escuelas de los niveles primario, secundario y terciario de la regi\u00f3n de influencia de la universidad o t\u00edtulo de profesor<\/p><p>&#8211; Completar el formulario de inscripci\u00f3n en el SIU GUARAN\u00cd.\u00a0<\/p><p>&#8211; Abonar la matr\u00edcula del curso.<\/p><p><strong>Importante:<\/strong> Los cursantes deber\u00e1n contar con conocimientos de inform\u00e1tica b\u00e1sica y disponibilidad de computadora con conexi\u00f3n a Internet.<\/p><p><strong>Aranceles:\u00a0<\/strong><\/p><p>&#8211; Matr\u00edcula (julio 2024) de $ 20.000 (el pago confirma la inscripci\u00f3n)<\/p><p>&#8211; 5 cuotas (agosto a diciembre 2024) de $40.000\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p><p>&#8211; 3 cuotas (febrero a abril 2025) de $ 48.000<\/p><p><strong>Consultas:\u00a0\u00a0<\/strong><a href=\"mailto:raquel.petris@comunidad.unne.edu.ar\">raquel.petris@comunidad.unne.edu.ar<\/a><\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sobre la propuesta Plan de Estudios Cuerpo acad\u00e9mico y de gesti\u00f3n Destinatarios Inscripci\u00f3n Sobre la propuesta Denominaci\u00f3n:\u00a0Diplomatura de Programaci\u00f3n y Rob\u00f3tica Educativa \u00a0 \u00a0 Plan de Estudios:\u00a0RES &#8211; 2024 &#8211; 4 &#8211; CD-EXA # UNNE \u00a0 Informaci\u00f3n de contacto:\u00a0raquel.petris@comunidad.unne.edu.ar\u00a0 \u00a0 Objetivos institucionales Acompa\u00f1ar las pol\u00edticas p\u00fablicas orientadas a incorporar en la educaci\u00f3n b\u00e1sica conceptos y &hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-185","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/exa.unne.edu.ar\/poee-web\/index.php\/wp-json\/wp\/v2\/pages\/185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exa.unne.edu.ar\/poee-web\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/exa.unne.edu.ar\/poee-web\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/exa.unne.edu.ar\/poee-web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exa.unne.edu.ar\/poee-web\/index.php\/wp-json\/wp\/v2\/comments?post=185"}],"version-history":[{"count":30,"href":"https:\/\/exa.unne.edu.ar\/poee-web\/index.php\/wp-json\/wp\/v2\/pages\/185\/revisions"}],"predecessor-version":[{"id":329,"href":"https:\/\/exa.unne.edu.ar\/poee-web\/index.php\/wp-json\/wp\/v2\/pages\/185\/revisions\/329"}],"wp:attachment":[{"href":"https:\/\/exa.unne.edu.ar\/poee-web\/index.php\/wp-json\/wp\/v2\/media?parent=185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exa.unne.edu.ar\/poee-web\/index.php\/wp-json\/wp\/v2\/categories?post=185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exa.unne.edu.ar\/poee-web\/index.php\/wp-json\/wp\/v2\/tags?post=185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}